{"id":247684,"date":"2021-12-17T12:28:44","date_gmt":"2021-12-17T11:28:44","guid":{"rendered":"https:\/\/www.overseas-association.eu\/?p=247684"},"modified":"2021-12-17T12:30:55","modified_gmt":"2021-12-17T11:30:55","slug":"nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice","status":"publish","type":"post","link":"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/","title":{"rendered":"Nouveaux appels \u00e0 propositions publi\u00e9s dans le cadre des programmes CERV et Justice"},"content":{"rendered":"<p>Le programme \u00ab\u00a0Citoyens, \u00e9galit\u00e9, droits et valeurs\u00a0\u00bb (CERV) est un programme de l&rsquo;UE qui soutient les organisations de la soci\u00e9t\u00e9 civile actives aux niveaux local, r\u00e9gional, national et transnational, qui travaillent dans les domaines de l&rsquo;inclusion, de l&rsquo;\u00e9galit\u00e9 des sexes, de la pr\u00e9vention de la violence ou de la d\u00e9mocratie. Les organisations bas\u00e9es dans les PTOM peuvent participer.<\/p>\n<p>Les appels \u00e0 propositions 2022 ont \u00e9t\u00e9 publi\u00e9s. 10 opportunit\u00e9s de financement abordant de multiples sujets tels que la d\u00e9mocratie, l&rsquo;\u00c9tat de droit, l&rsquo;engagement des citoyens, la lutte contre le racisme, la x\u00e9nophobie et la discrimination, l&rsquo;\u00e9galit\u00e9 des sexes, les droits de l&rsquo;enfant, etc.<\/p>\n<p>Toutes les informations sur les nouveaux appels \u00e0 propositions du CERV se trouvent ici : <a href=\"https:\/\/ec.europa.eu\/newsroom\/just\/items\/728082\/en\">https:\/\/ec.europa.eu\/newsroom\/just\/items\/728082\/en<\/a>.<\/p>\n<p>N&rsquo;h\u00e9sitez pas \u00e0 nous contacter si vous souhaitez de plus amples informations. L&rsquo;OCTA a organis\u00e9 avec la Commission europ\u00e9enne un webinaire pour pr\u00e9senter le CERV et les nouveaux appels aux PTOM le 9 d\u00e9cembre 2021, les pr\u00e9sentations peuvent \u00eatre t\u00e9l\u00e9charg\u00e9es sur le site de l&rsquo;\u00e9v\u00e9nement : <a href=\"https:\/\/www.overseas-association.eu\/event\/eu-programmes-webinar-citizens-equality-rights-and-values-programme-cerv\/\">https:\/\/www.overseas-association.eu\/event\/eu-programmes-webinar-citizens-equality-rights-and-values-programme-cerv\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le programme \u00ab\u00a0Citoyens, \u00e9galit\u00e9, droits et valeurs\u00a0\u00bb (CERV) est un programme de l&rsquo;UE qui soutient les organisations de la soci\u00e9t\u00e9 civile actives aux niveaux local, r\u00e9gional, national et transnational, qui travaillent dans les domaines de l&rsquo;inclusion, de l&rsquo;\u00e9galit\u00e9 des sexes, de la pr\u00e9vention de la violence ou de la d\u00e9mocratie. Les organisations bas\u00e9es dans les [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":247745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[239],"tags":[],"event_type":[],"class_list":["post-247684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouveaux appels \u00e0 propositions publi\u00e9s dans le cadre des programmes CERV et Justice - OCTA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouveaux appels \u00e0 propositions publi\u00e9s dans le cadre des programmes CERV et Justice - OCTA\" \/>\n<meta property=\"og:description\" content=\"Le programme \u00ab\u00a0Citoyens, \u00e9galit\u00e9, droits et valeurs\u00a0\u00bb (CERV) est un programme de l&rsquo;UE qui soutient les organisations de la soci\u00e9t\u00e9 civile actives aux niveaux local, r\u00e9gional, national et transnational, qui travaillent dans les domaines de l&rsquo;inclusion, de l&rsquo;\u00e9galit\u00e9 des sexes, de la pr\u00e9vention de la violence ou de la d\u00e9mocratie. Les organisations bas\u00e9es dans les [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/\" \/>\n<meta property=\"og:site_name\" content=\"OCTA\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-17T11:28:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-17T11:30:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.overseas-association.eu\/content\/uploads\/2021\/12\/Capturecalls-cerv-2022-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"586\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Fern\u00e1ndez Fornieles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Fern\u00e1ndez Fornieles\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\\\/\"},\"author\":{\"name\":\"Marta Fern\u00e1ndez Fornieles\",\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/#\\\/schema\\\/person\\\/ba93d459c87253e3c8a3dd21e4e00c00\"},\"headline\":\"Nouveaux appels \u00e0 propositions publi\u00e9s dans le cadre des programmes CERV et Justice\",\"datePublished\":\"2021-12-17T11:28:44+00:00\",\"dateModified\":\"2021-12-17T11:30:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\\\/\"},\"wordCount\":209,\"publisher\":{\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.overseas-association.eu\\\/content\\\/uploads\\\/2021\\\/12\\\/Capturecalls-cerv-2022-1.jpg\",\"articleSection\":[\"ACTUALITE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\\\/\",\"url\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\\\/\",\"name\":\"Nouveaux appels \u00e0 propositions publi\u00e9s dans le cadre des programmes CERV et Justice - OCTA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.overseas-association.eu\\\/content\\\/uploads\\\/2021\\\/12\\\/Capturecalls-cerv-2022-1.jpg\",\"datePublished\":\"2021-12-17T11:28:44+00:00\",\"dateModified\":\"2021-12-17T11:30:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.overseas-association.eu\\\/content\\\/uploads\\\/2021\\\/12\\\/Capturecalls-cerv-2022-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.overseas-association.eu\\\/content\\\/uploads\\\/2021\\\/12\\\/Capturecalls-cerv-2022-1.jpg\",\"width\":586,\"height\":423},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouveaux appels \u00e0 propositions publi\u00e9s dans le cadre des programmes CERV et Justice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/\",\"name\":\"OCTA\",\"description\":\"Overseas Countries and Territories Association\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/#organization\",\"name\":\"Overseas Countries and Territories Association\",\"url\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.overseas-association.eu\\\/content\\\/uploads\\\/2021\\\/03\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.overseas-association.eu\\\/content\\\/uploads\\\/2021\\\/03\\\/logo.png\",\"width\":316,\"height\":134,\"caption\":\"Overseas Countries and Territories Association\"},\"image\":{\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/#\\\/schema\\\/person\\\/ba93d459c87253e3c8a3dd21e4e00c00\",\"name\":\"Marta Fern\u00e1ndez Fornieles\",\"url\":\"https:\\\/\\\/www.overseas-association.eu\\\/fr\\\/author\\\/marta_octa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouveaux appels \u00e0 propositions publi\u00e9s dans le cadre des programmes CERV et Justice - OCTA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouveaux appels \u00e0 propositions publi\u00e9s dans le cadre des programmes CERV et Justice - OCTA","og_description":"Le programme \u00ab\u00a0Citoyens, \u00e9galit\u00e9, droits et valeurs\u00a0\u00bb (CERV) est un programme de l&rsquo;UE qui soutient les organisations de la soci\u00e9t\u00e9 civile actives aux niveaux local, r\u00e9gional, national et transnational, qui travaillent dans les domaines de l&rsquo;inclusion, de l&rsquo;\u00e9galit\u00e9 des sexes, de la pr\u00e9vention de la violence ou de la d\u00e9mocratie. Les organisations bas\u00e9es dans les [&hellip;]","og_url":"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/","og_site_name":"OCTA","article_published_time":"2021-12-17T11:28:44+00:00","article_modified_time":"2021-12-17T11:30:55+00:00","og_image":[{"width":586,"height":423,"url":"https:\/\/www.overseas-association.eu\/content\/uploads\/2021\/12\/Capturecalls-cerv-2022-1.jpg","type":"image\/jpeg"}],"author":"Marta Fern\u00e1ndez Fornieles","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marta Fern\u00e1ndez Fornieles","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/#article","isPartOf":{"@id":"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/"},"author":{"name":"Marta Fern\u00e1ndez Fornieles","@id":"https:\/\/www.overseas-association.eu\/fr\/#\/schema\/person\/ba93d459c87253e3c8a3dd21e4e00c00"},"headline":"Nouveaux appels \u00e0 propositions publi\u00e9s dans le cadre des programmes CERV et Justice","datePublished":"2021-12-17T11:28:44+00:00","dateModified":"2021-12-17T11:30:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/"},"wordCount":209,"publisher":{"@id":"https:\/\/www.overseas-association.eu\/fr\/#organization"},"image":{"@id":"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/#primaryimage"},"thumbnailUrl":"https:\/\/www.overseas-association.eu\/content\/uploads\/2021\/12\/Capturecalls-cerv-2022-1.jpg","articleSection":["ACTUALITE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/","url":"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/","name":"Nouveaux appels \u00e0 propositions publi\u00e9s dans le cadre des programmes CERV et Justice - OCTA","isPartOf":{"@id":"https:\/\/www.overseas-association.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/#primaryimage"},"image":{"@id":"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/#primaryimage"},"thumbnailUrl":"https:\/\/www.overseas-association.eu\/content\/uploads\/2021\/12\/Capturecalls-cerv-2022-1.jpg","datePublished":"2021-12-17T11:28:44+00:00","dateModified":"2021-12-17T11:30:55+00:00","breadcrumb":{"@id":"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/#primaryimage","url":"https:\/\/www.overseas-association.eu\/content\/uploads\/2021\/12\/Capturecalls-cerv-2022-1.jpg","contentUrl":"https:\/\/www.overseas-association.eu\/content\/uploads\/2021\/12\/Capturecalls-cerv-2022-1.jpg","width":586,"height":423},{"@type":"BreadcrumbList","@id":"https:\/\/www.overseas-association.eu\/fr\/nouveaux-appels-a-propositions-publies-dans-le-cadre-des-programmes-cerv-et-justice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.overseas-association.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouveaux appels \u00e0 propositions publi\u00e9s dans le cadre des programmes CERV et Justice"}]},{"@type":"WebSite","@id":"https:\/\/www.overseas-association.eu\/fr\/#website","url":"https:\/\/www.overseas-association.eu\/fr\/","name":"OCTA","description":"Overseas Countries and Territories Association","publisher":{"@id":"https:\/\/www.overseas-association.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.overseas-association.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.overseas-association.eu\/fr\/#organization","name":"Overseas Countries and Territories Association","url":"https:\/\/www.overseas-association.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.overseas-association.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.overseas-association.eu\/content\/uploads\/2021\/03\/logo.png","contentUrl":"https:\/\/www.overseas-association.eu\/content\/uploads\/2021\/03\/logo.png","width":316,"height":134,"caption":"Overseas Countries and Territories Association"},"image":{"@id":"https:\/\/www.overseas-association.eu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.overseas-association.eu\/fr\/#\/schema\/person\/ba93d459c87253e3c8a3dd21e4e00c00","name":"Marta Fern\u00e1ndez Fornieles","url":"https:\/\/www.overseas-association.eu\/fr\/author\/marta_octa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.overseas-association.eu\/fr\/wp-json\/wp\/v2\/posts\/247684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.overseas-association.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.overseas-association.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.overseas-association.eu\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.overseas-association.eu\/fr\/wp-json\/wp\/v2\/comments?post=247684"}],"version-history":[{"count":0,"href":"https:\/\/www.overseas-association.eu\/fr\/wp-json\/wp\/v2\/posts\/247684\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.overseas-association.eu\/fr\/wp-json\/wp\/v2\/media\/247745"}],"wp:attachment":[{"href":"https:\/\/www.overseas-association.eu\/fr\/wp-json\/wp\/v2\/media?parent=247684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.overseas-association.eu\/fr\/wp-json\/wp\/v2\/categories?post=247684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.overseas-association.eu\/fr\/wp-json\/wp\/v2\/tags?post=247684"},{"taxonomy":"event_type","embeddable":true,"href":"https:\/\/www.overseas-association.eu\/fr\/wp-json\/wp\/v2\/event_type?post=247684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}